{"id":6629,"date":"2025-11-18T09:47:59","date_gmt":"2025-11-18T08:47:59","guid":{"rendered":"https:\/\/zehnderhurter.ch\/movec-interfaces\/"},"modified":"2026-05-26T08:04:56","modified_gmt":"2026-05-26T06:04:56","slug":"movec-interfaces","status":"publish","type":"page","link":"https:\/\/zehnderhurter.ch\/fr\/movec-interfaces\/","title":{"rendered":"movec &#8211; Interfaces"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/zehnderhurter.ch\/wp-content\/uploads\/2025\/11\/OEM_Schnittstelle_Header.png\u00a0\u00bb height=\u00a0\u00bb500px\u00a0\u00bb custom_margin=\u00a0\u00bb-80px||||false|false\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset6&Prime; box_shadow_blur=\u00a0\u00bb30px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_module=\u00a0\u00bb4670&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_button button_url=\u00a0\u00bbhttps:\/\/zehnderhurter.ch\/kontakt-support\/#Kontakt-Telefon\u00a0\u00bb button_text=\u00a0\u00bbSupport et contact\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb28px\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bb#57a4dd\u00a0\u00bb button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb20px\u00a0\u00bb button_font=\u00a0\u00bb|300|||||||\u00a0\u00bb button_icon=\u00a0\u00bb&#xe028;||divi||400&Prime; button_icon_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_icon_placement=\u00a0\u00bbleft\u00a0\u00bb button_on_hover=\u00a0\u00bboff\u00a0\u00bb positioning=\u00a0\u00bbfixed\u00a0\u00bb position_origin_f=\u00a0\u00bbcenter_right\u00a0\u00bb horizontal_offset=\u00a0\u00bb-333px\u00a0\u00bb z_index=\u00a0\u00bb9999&Prime; custom_margin=\u00a0\u00bb138px|0px|0px|0px|false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|100px|||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb position_origin_f__hover_enabled=\u00a0\u00bbon|desktop\u00a0\u00bb positioning__hover_enabled=\u00a0\u00bbon|desktop\u00a0\u00bb position_origin_a__hover_enabled=\u00a0\u00bbon|desktop\u00a0\u00bb position_origin_r__hover_enabled=\u00a0\u00bbon|desktop\u00a0\u00bb horizontal_offset__hover_enabled=\u00a0\u00bbon|desktop\u00a0\u00bb horizontal_offset__hover=\u00a0\u00bb-80px\u00a0\u00bb position_origin_f__hover=\u00a0\u00bbcenter_right\u00a0\u00bb positioning__hover=\u00a0\u00bbfixed\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb button_bg_color__hover=\u00a0\u00bb#2b4d76&Prime; button_bg_enable_color__hover=\u00a0\u00bbon\u00a0\u00bb][\/et_pb_button][et_pb_button button_url=\u00a0\u00bbtel:+41442445880&Prime; button_text=\u00a0\u00bb+41 44 244 58 80&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb28px\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bb#57a4dd\u00a0\u00bb button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb20px\u00a0\u00bb button_font=\u00a0\u00bb|300|||||||\u00a0\u00bb button_icon=\u00a0\u00bb&#xf879;||fa||900&Prime; button_icon_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_icon_placement=\u00a0\u00bbleft\u00a0\u00bb button_on_hover=\u00a0\u00bboff\u00a0\u00bb positioning=\u00a0\u00bbfixed\u00a0\u00bb position_origin_f=\u00a0\u00bbcenter_right\u00a0\u00bb horizontal_offset=\u00a0\u00bb-320px\u00a0\u00bb z_index=\u00a0\u00bb9999&Prime; custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|100px|||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb position_origin_f__hover_enabled=\u00a0\u00bbon|desktop\u00a0\u00bb positioning__hover_enabled=\u00a0\u00bbon|desktop\u00a0\u00bb position_origin_a__hover_enabled=\u00a0\u00bbon|desktop\u00a0\u00bb position_origin_r__hover_enabled=\u00a0\u00bbon|desktop\u00a0\u00bb horizontal_offset__hover_enabled=\u00a0\u00bbon|desktop\u00a0\u00bb horizontal_offset__hover=\u00a0\u00bb-80px\u00a0\u00bb position_origin_f__hover=\u00a0\u00bbcenter_right\u00a0\u00bb positioning__hover=\u00a0\u00bbfixed\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb button_bg_color__hover=\u00a0\u00bb#2b4d76&Prime; button_bg_enable_color__hover=\u00a0\u00bbon\u00a0\u00bb][\/et_pb_button][et_pb_button button_url=\u00a0\u00bbmailto:mail@zehnderhurter.ch\u00a0\u00bb button_text=\u00a0\u00bbmail@zehnderhurter.ch\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb28px\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bb#57a4dd\u00a0\u00bb button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb20px\u00a0\u00bb button_font=\u00a0\u00bb|300|||||||\u00a0\u00bb button_icon=\u00a0\u00bb&#xe076;||divi||400&Prime; button_icon_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_icon_placement=\u00a0\u00bbleft\u00a0\u00bb button_on_hover=\u00a0\u00bboff\u00a0\u00bb positioning=\u00a0\u00bbfixed\u00a0\u00bb position_origin_f=\u00a0\u00bbcenter_right\u00a0\u00bb horizontal_offset=\u00a0\u00bb-378px\u00a0\u00bb z_index=\u00a0\u00bb9999&Prime; custom_margin=\u00a0\u00bb69px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|100px|||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb position_origin_f__hover_enabled=\u00a0\u00bbon|desktop\u00a0\u00bb positioning__hover_enabled=\u00a0\u00bbon|desktop\u00a0\u00bb position_origin_a__hover_enabled=\u00a0\u00bbon|desktop\u00a0\u00bb position_origin_r__hover_enabled=\u00a0\u00bbon|desktop\u00a0\u00bb horizontal_offset__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb horizontal_offset__hover=\u00a0\u00bb-80px\u00a0\u00bb position_origin_f__hover=\u00a0\u00bbcenter_right\u00a0\u00bb positioning__hover=\u00a0\u00bbfixed\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb button_bg_color__hover=\u00a0\u00bb#2b4d76&Prime; button_bg_enable_color__hover=\u00a0\u00bbon\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bbon|on|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb positioning=\u00a0\u00bbfixed\u00a0\u00bb position_origin_a=\u00a0\u00bbtop_center\u00a0\u00bb position_origin_f=\u00a0\u00bbtop_center\u00a0\u00bb vertical_offset=\u00a0\u00bb76px\u00a0\u00bb z_index=\u00a0\u00bb500&Prime; custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb animation_delay=\u00a0\u00bb50ms\u00a0\u00bb scroll_vertical_motion=\u00a0\u00bb0|65|65|100|4|0|-4&Prime; motion_trigger_start=\u00a0\u00bbtop\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset3&Prime; box_shadow_vertical=\u00a0\u00bb2px\u00a0\u00bb box_shadow_blur=\u00a0\u00bb22px\u00a0\u00bb global_module=\u00a0\u00bb5723&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_menu menu_id=\u00a0\u00bb123&Prime; active_link_color=\u00a0\u00bbgcid-cee353b0-e1a2-4da5-a40e-597c009a23d0&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb menu_font=\u00a0\u00bb|600|||||||\u00a0\u00bb background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb module_alignment=\u00a0\u00bbleft\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-cee353b0-e1a2-4da5-a40e-597c009a23d0%22:%91%22active_link_color%22%93}\u00a0\u00bb][\/et_pb_menu][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb30px||||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb107px\u00a0\u00bb custom_margin=\u00a0\u00bb-36px|auto||auto||\u00a0\u00bb custom_padding=\u00a0\u00bb||30px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_heading title=\u00a0\u00bbOEM \u2013 Solutions num\u00e9riques pour les constructeurs automobiles et les organisations d&#039;importation\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_text_align=\u00a0\u00bbleft\u00a0\u00bb title_font_size=\u00a0\u00bb33px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||20px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3><b>Que signifie OEM \u2013 et pourquoi est-ce si important ?<\/b><\/h3>\n<p><b>OEM<\/b> signifie <i>Original Equipment Manufacturer<\/i> \u2013 c&rsquo;est-\u00e0-dire le <b>constructeur automobile ou \u00e9quipementier d&rsquo;origine<\/b> qui produit des voitures, des v\u00e9hicules utilitaires ou des motos et les distribue \u00e0 la client\u00e8le via des <b>importateurs et concessionnaires<\/b>.<\/p>\n<p>Pour que ces r\u00e9seaux complexes collaborent efficacement, il faut des <b>interfaces num\u00e9riques<\/b> et des <b>plateformes de donn\u00e9es communes<\/b>.<\/p>\n<p>C&rsquo;est l\u00e0 qu&rsquo;intervient <b>movec<\/b>.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb3_5,2_5&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb3_5&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3><b>Pourquoi les int\u00e9grations OEM sont \u00e9galement pertinentes pour les garages<\/b><\/h3>\n<p>Les garages travaillent quotidiennement avec les syst\u00e8mes des diff\u00e9rents constructeurs automobiles \u2013 que ce soit pour le <b>service, la garantie, les pi\u00e8ces d\u00e9tach\u00e9es ou les campagnes<\/b>.<\/p>\n<p>Gr\u00e2ce aux <b>interfaces OEM<\/b> int\u00e9gr\u00e9es, toutes les informations importantes peuvent \u00eatre \u00e9chang\u00e9es automatiquement :<\/p>\n<p>Les donn\u00e9es v\u00e9hicules et clients, les intervalles d&rsquo;entretien, les rappels, les documentations techniques ou les informations sur les pi\u00e8ces sont disponibles <b>directement dans le DMS<\/b>.<\/p>\n<p>Cela signifie pour l&rsquo;entreprise :<\/p>\n<ul>\n<li>moins de saisies manuelles \u2192 moins d&rsquo;erreurs<\/li>\n<li>processus de service plus rapides<\/li>\n<li>normes de donn\u00e9es actuelles conformes aux exigences des constructeurs<\/li>\n<li>et une pr\u00e9sentation professionnelle et conforme \u00e0 la marque vis-\u00e0-vis de la client\u00e8le et de l&rsquo;importateur<\/li>\n<\/ul>\n<p>En bref :<\/p>\n<p><b>Les interfaces OEM cr\u00e9ent efficacit\u00e9, transparence et s\u00e9curit\u00e9 \u2013 et aident les garages \u00e0 travailler comme les constructeurs l&rsquo;attendent.<\/b><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb2_5&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/zehnderhurter.ch\/wp-content\/uploads\/2025\/11\/OEM_Importeure.png\u00a0\u00bb title_text=\u00a0\u00bbOEM_Importeurs\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; box_shadow_style=\u00a0\u00bbpreset1&Prime; box_shadow_blur=\u00a0\u00bb8px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3><b>movec \u2013 le pont num\u00e9rique entre constructeur, importateur et entreprise<\/b><\/h3>\n<p>Nos solutions connectent les <b>syst\u00e8mes OEM, les importateurs et les garages<\/b> via des interfaces standardis\u00e9es ou d\u00e9velopp\u00e9es sur mesure. Ainsi, les donn\u00e9es relatives aux <b>v\u00e9hicules, clients, services, pi\u00e8ces et garanties<\/b> sont automatiquement synchronis\u00e9es \u2013 rapidement, en toute s\u00e9curit\u00e9 et de mani\u00e8re transparente. <\/p>\n<p>Les <b>int\u00e9grations OEM<\/b><b> <\/b><b>movec<\/b> garantissent que tous les acteurs du cycle de vie du v\u00e9hicule travaillent sur la m\u00eame base de donn\u00e9es.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2><strong>Avantages pour les OEM, les importateurs et les garages<\/strong><\/h2>\n<ul>\n<li><strong>Gestion centralis\u00e9e des donn\u00e9es<\/strong> \u2013 donn\u00e9es v\u00e9hicules, clients et services actuelles disponibles en temps r\u00e9el<\/li>\n<li><strong>Int\u00e9gration r\u00e9seau simplifi\u00e9e<\/strong> \u2013 communication efficace entre constructeurs, importateurs et entreprises partenaires<\/li>\n<li><strong>Interfaces certifi\u00e9es<\/strong> \u2013 connexions OEM v\u00e9rifi\u00e9es pour de nombreuses marques<\/li>\n<li><strong>Solutions en marque blanche<\/strong> \u2013 d\u00e9ployables individuellement dans le design corporate de la marque<\/li>\n<li><strong>Qualit\u00e9 et transparence des donn\u00e9es accrues<\/strong> \u2013 aucune rupture de support, aucune perte d&rsquo;information<\/li>\n<li><strong>Flexible et \u00e9volutif<\/strong> \u2013 adapt\u00e9 aux marques individuelles, aux r\u00e9seaux d&rsquo;importation ou aux OEM op\u00e9rant \u00e0 l&rsquo;\u00e9chelle mondiale<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1 style=\"text-align: center;\"><strong>Aper\u00e7u des interfaces constructeurs<\/strong><\/h1>\n<p style=\"text-align: center;\">movec dispose d&rsquo;int\u00e9grations OEM avec des marques renomm\u00e9es, notamment :<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_4,1_4,1_4,1_4&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbrgba(0,0,0,0.04)\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb border_radii=\u00a0\u00bbon|20px|20px|20px|20px\u00a0\u00bb border_width_all=\u00a0\u00bb1px\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset1&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_heading title=\u00a0\u00bbMarques VP\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_text_align=\u00a0\u00bbcenter\u00a0\u00bb title_font_size=\u00a0\u00bb18px\u00a0\u00bb custom_margin=\u00a0\u00bb15px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_heading][et_pb_image src=\u00a0\u00bbhttps:\/\/zehnderhurter.ch\/wp-content\/uploads\/2025\/11\/marken_PKW.png\u00a0\u00bb title_text=\u00a0\u00bbmarques_VP\u00a0\u00bb show_in_lightbox=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbrgba(0,0,0,0.04)\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb border_radii=\u00a0\u00bbon|20px|20px|20px|20px\u00a0\u00bb border_width_all=\u00a0\u00bb1px\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset1&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_heading title=\u00a0\u00bbMarques v\u00e9hicules utilitaires\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_text_align=\u00a0\u00bbcenter\u00a0\u00bb title_font_size=\u00a0\u00bb18px\u00a0\u00bb custom_margin=\u00a0\u00bb15px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_heading][et_pb_image src=\u00a0\u00bbhttps:\/\/zehnderhurter.ch\/wp-content\/uploads\/2025\/11\/marken_Nutzfahrzeuge.png\u00a0\u00bb title_text=\u00a0\u00bbmarques_V\u00e9hicules_utilitaires\u00a0\u00bb show_in_lightbox=\u00a0\u00bbon\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbrgba(0,0,0,0.04)\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbtop\u00a0\u00bb border_radii=\u00a0\u00bbon|20px|20px|20px|20px\u00a0\u00bb border_width_all=\u00a0\u00bb1px\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset1&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_heading title=\u00a0\u00bbMarques machines agricoles\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_text_align=\u00a0\u00bbcenter\u00a0\u00bb title_font_size=\u00a0\u00bb18px\u00a0\u00bb custom_margin=\u00a0\u00bb15px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_heading][et_pb_image src=\u00a0\u00bbhttps:\/\/zehnderhurter.ch\/wp-content\/uploads\/2025\/11\/marken_Landtechnik.png\u00a0\u00bb title_text=\u00a0\u00bbmarques_Machines_agricoles\u00a0\u00bb show_in_lightbox=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbrgba(0,0,0,0.04)\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbright\u00a0\u00bb border_radii=\u00a0\u00bbon|20px|20px|20px|20px\u00a0\u00bb border_width_all=\u00a0\u00bb1px\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset1&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_heading title=\u00a0\u00bbMarques deux-roues\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_text_align=\u00a0\u00bbcenter\u00a0\u00bb title_font_size=\u00a0\u00bb18px\u00a0\u00bb custom_margin=\u00a0\u00bb15px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_heading][et_pb_image src=\u00a0\u00bbhttps:\/\/zehnderhurter.ch\/wp-content\/uploads\/2025\/11\/Marken_Zweirad.png\u00a0\u00bb title_text=\u00a0\u00bbMarques_Deux-roues\u00a0\u00bb show_in_lightbox=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Ces interfaces permettent une <strong>communication fluide<\/strong> entre constructeur, importateur, r\u00e9seau de concessionnaires et client\u00e8le finale \u2013 de la commande du v\u00e9hicule \u00e0 l&rsquo;entretien et la garantie jusqu&rsquo;au service apr\u00e8s-vente.<\/p>\n<h2><strong>Votre partenaire pour les int\u00e9grations OEM<\/strong><\/h2>\n<p>movec comprend les exigences des OEM internationaux, des organisations d&rsquo;importation et des r\u00e9seaux de concessionnaires.<br \/>Nos solutions sont <strong>certifi\u00e9es, s\u00e9curis\u00e9es et enti\u00e8rement int\u00e9gr\u00e9es<\/strong> \u2013 pour un \u00e9change de donn\u00e9es fluide tout au long de la cha\u00eene de valeur.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb3_4,1_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb35px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2><strong>Autres interfaces pour nos garagistes suisses<\/strong><\/h2>\n<p>Outre les int\u00e9grations OEM, movec \/ motionData DMS propose de nombreuses interfaces vers les syst\u00e8mes fournisseurs, syst\u00e8mes de pi\u00e8ces et solutions partenaires, afin que vos processus restent \u00e9galement parfaitement connect\u00e9s en dehors du monde des constructeurs.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/zehnderhurter.ch\/wp-content\/uploads\/2025\/11\/ch-e1763455242266.png\u00a0\u00bb title_text=\u00a0\u00bbGaragistes suisses\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][divi8_image_carousel _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb divi8_arrow_icon_show_hide=\u00a0\u00bbon\u00a0\u00bb divi8_left_icon=\u00a0\u00bbD||divi||400&Prime; divi8_right_icon=\u00a0\u00bbE||divi||400&Prime; sticky_enabled=\u00a0\u00bb0&Prime;][divi8_image_carousel_item img=\u00a0\u00bbhttps:\/\/zehnderhurter.ch\/wp-content\/uploads\/2025\/11\/logo_hostettler.png\u00a0\u00bb divi8_image_content_position=\u00a0\u00bbnone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/divi8_image_carousel_item][divi8_image_carousel_item img=\u00a0\u00bbhttps:\/\/zehnderhurter.ch\/wp-content\/uploads\/2025\/11\/logo_ESA.png\u00a0\u00bb divi8_image_content_position=\u00a0\u00bbnone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/divi8_image_carousel_item][divi8_image_carousel_item img=\u00a0\u00bbhttps:\/\/zehnderhurter.ch\/wp-content\/uploads\/2025\/11\/logo_Derendinger.png\u00a0\u00bb divi8_image_content_position=\u00a0\u00bbnone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/divi8_image_carousel_item][divi8_image_carousel_item img=\u00a0\u00bbhttps:\/\/zehnderhurter.ch\/wp-content\/uploads\/2025\/11\/logo_bmd.png\u00a0\u00bb divi8_image_content_position=\u00a0\u00bbnone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/divi8_image_carousel_item][divi8_image_carousel_item img=\u00a0\u00bbhttps:\/\/zehnderhurter.ch\/wp-content\/uploads\/2025\/11\/logo_autoi.png\u00a0\u00bb divi8_image_content_position=\u00a0\u00bbnone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/divi8_image_carousel_item][divi8_image_carousel_item img=\u00a0\u00bbhttps:\/\/zehnderhurter.ch\/wp-content\/uploads\/2025\/11\/logo_audatex.png\u00a0\u00bb divi8_image_content_position=\u00a0\u00bbnone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/divi8_image_carousel_item][divi8_image_carousel_item img=\u00a0\u00bbhttps:\/\/zehnderhurter.ch\/wp-content\/uploads\/2025\/11\/ch-e1763455242266.png\u00a0\u00bb divi8_image_content_position=\u00a0\u00bbnone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/divi8_image_carousel_item][\/divi8_image_carousel][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; next_background_color=\u00a0\u00bb#ffffff\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbgcid-cee353b0-e1a2-4da5-a40e-597c009a23d0&Prime; custom_margin=\u00a0\u00bb70px||70px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb top_divider_height=\u00a0\u00bb30px\u00a0\u00bb bottom_divider_style=\u00a0\u00bbarrow\u00a0\u00bb bottom_divider_height=\u00a0\u00bb30px\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-cee353b0-e1a2-4da5-a40e-597c009a23d0%22:%91%22background_color%22%93}\u00a0\u00bb][et_pb_row custom_padding_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb transform_scale=\u00a0\u00bb102%|102%\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb40px|40px|40px|40px|false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb40px|40px|40px|40px|false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb40px|20px|40px|20px|false|false\u00a0\u00bb border_radii=\u00a0\u00bbon|15px|15px|15px|15px\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-cee353b0-e1a2-4da5-a40e-597c009a23d0%22:%91%22background_color%22%93}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_heading title=\u00a0\u00bbmovec \u2013 votre connexion num\u00e9rique \u00e0 l&#039;ensemble du monde automobile.\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_text_align=\u00a0\u00bbcenter\u00a0\u00bb title_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb title_font_size=\u00a0\u00bb36px\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb title_font_size_tablet=\u00a0\u00bb26px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_heading][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb-50px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb text_line_height=\u00a0\u00bb1.8em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Du <strong>constructeur au fournisseur de pi\u00e8ces<\/strong>, de <strong>l&rsquo;importateur \u00e0 la comptabilit\u00e9 financi\u00e8re<\/strong> \u2013 movec \/ motionData DMS connecte tout ce qui fait avancer votre garage.<\/p>\n<p>Les interfaces OEM certifi\u00e9es et les nombreuses int\u00e9grations partenaires garantissent des processus transparents, l&rsquo;automatisation et l&rsquo;efficacit\u00e9 \u2013 le tout dans une plateforme qui \u00e9volue avec votre entreprise.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\"><strong>Nous disposons de nombreuses autres interfaces \u2013 pour toute question, contactez-nous ici.<\/strong><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider divider_style=\u00a0\u00bbnone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbgcid-cee353b0-e1a2-4da5-a40e-597c009a23d0&Prime; custom_padding=\u00a0\u00bb0px||20px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-cee353b0-e1a2-4da5-a40e-597c009a23d0%22:%91%22background_color%22%93}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb transform_translate=\u00a0\u00bb0px|-111px\u00a0\u00bb transform_translate_linked=\u00a0\u00bboff\u00a0\u00bb custom_margin=\u00a0\u00bb||-100px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_module=\u00a0\u00bb5435&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_css_main_element_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_css_main_element_tablet=\u00a0\u00bbdisplay: flex;\u00a0\u00bb custom_css_main_element_phone=\u00a0\u00bb \u00ab\u00a0][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/zehnderhurter.ch\/wp-content\/uploads\/2025\/11\/10.png\u00a0\u00bb title_text=\u00a0\u00bbMichael Zehnder\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb50%\u00a0\u00bb max_width_tablet=\u00a0\u00bb60%\u00a0\u00bb max_width_phone=\u00a0\u00bb60%\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb border_radii=\u00a0\u00bbon|200px|200px|200px|200px\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset1&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_3_font=\u00a0\u00bb|600|||||||\u00a0\u00bb header_3_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_3_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Michael Zehnder<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/zehnderhurter.ch\/wp-content\/uploads\/2025\/11\/8-2.png\u00a0\u00bb title_text=\u00a0\u00bbNuno Peixoto\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb50%\u00a0\u00bb max_width_tablet=\u00a0\u00bb60%\u00a0\u00bb max_width_phone=\u00a0\u00bb60%\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb border_radii=\u00a0\u00bbon|200px|200px|200px|200px\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset1&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_3_font=\u00a0\u00bb|600|||||||\u00a0\u00bb header_3_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_3_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Nuno Peixoto<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/zehnderhurter.ch\/wp-content\/uploads\/2025\/11\/Mitarbeiter-Fotos-ConsultInvest.png\u00a0\u00bb title_text=\u00a0\u00bbMarcel Reif\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb50%\u00a0\u00bb max_width_tablet=\u00a0\u00bb60%\u00a0\u00bb max_width_phone=\u00a0\u00bb60%\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb border_radii=\u00a0\u00bbon|200px|200px|200px|200px\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset1&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_3_font=\u00a0\u00bb|600|||||||\u00a0\u00bb header_3_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_3_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Marcel Reif<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_module=\u00a0\u00bb4530&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_2_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_2_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|600|||||||\u00a0\u00bb header_3_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_3_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Contactez-nous d\u00e8s maintenant<\/h2>\n<h3>D\u00e9marrez maintenant et prenez rendez-vous<\/h3>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/zehnderhurter.ch\/kontakt-support\/#Contactform\u00a0\u00bb button_text=\u00a0\u00bbEntretien initial gratuit\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bbgcid-7ed2b47d-ac4a-45d0-b6e3-7b63438d89e1&Prime; button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb30px\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-7ed2b47d-ac4a-45d0-b6e3-7b63438d89e1%22:%91%22button_bg_color%22%93}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Que signifie OEM \u2013 et pourquoi est-ce si important ? OEM signifie Original Equipment Manufacturer \u2013 c&rsquo;est-\u00e0-dire le constructeur automobile ou \u00e9quipementier d&rsquo;origine qui produit des voitures, des v\u00e9hicules utilitaires ou des motos et les distribue \u00e0 la client\u00e8le via des importateurs et concessionnaires. Pour que ces r\u00e9seaux complexes collaborent efficacement, il faut des interfaces [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":6574,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-6629","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>movec - Interfaces - Zehnder &amp; Hurter AG<\/title>\n<meta name=\"description\" content=\"movec interfaces OEM \u2013 Solutions num\u00e9riques pour les constructeurs automobiles et les organisations d&#039;importation\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zehnderhurter.ch\/fr\/movec-interfaces\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"movec - Interfaces - Zehnder &amp; Hurter AG\" \/>\n<meta property=\"og:description\" content=\"movec interfaces OEM \u2013 Solutions num\u00e9riques pour les constructeurs automobiles et les organisations d&#039;importation\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zehnderhurter.ch\/fr\/movec-interfaces\/\" \/>\n<meta property=\"og:site_name\" content=\"Zehnder &amp; Hurter AG\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-26T06:04:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zehnderhurter.ch\/wp-content\/uploads\/2025\/11\/OEM_Schnittstelle_Header.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"18 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zehnderhurter.ch\\\/fr\\\/movec-interfaces\\\/\",\"url\":\"https:\\\/\\\/zehnderhurter.ch\\\/fr\\\/movec-interfaces\\\/\",\"name\":\"movec - Interfaces - Zehnder &amp; Hurter AG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zehnderhurter.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zehnderhurter.ch\\\/fr\\\/movec-interfaces\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zehnderhurter.ch\\\/fr\\\/movec-interfaces\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zehnderhurter.ch\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/OEM_Schnittstelle_Header.png\",\"datePublished\":\"2025-11-18T08:47:59+00:00\",\"dateModified\":\"2026-05-26T06:04:56+00:00\",\"description\":\"movec interfaces OEM \u2013 Solutions num\u00e9riques pour les constructeurs automobiles et les organisations d'importation\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zehnderhurter.ch\\\/fr\\\/movec-interfaces\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zehnderhurter.ch\\\/fr\\\/movec-interfaces\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/zehnderhurter.ch\\\/fr\\\/movec-interfaces\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zehnderhurter.ch\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/OEM_Schnittstelle_Header.png\",\"contentUrl\":\"https:\\\/\\\/zehnderhurter.ch\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/OEM_Schnittstelle_Header.png\",\"width\":1800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zehnderhurter.ch\\\/fr\\\/movec-interfaces\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zehnderhurter.ch\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"movec &#8211; Interfaces\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zehnderhurter.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/zehnderhurter.ch\\\/fr\\\/\",\"name\":\"Zehnder &amp; Hurter AG\",\"description\":\"Zehnder &amp; Hurter AG\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zehnderhurter.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"movec - Interfaces - Zehnder &amp; Hurter AG","description":"movec interfaces OEM \u2013 Solutions num\u00e9riques pour les constructeurs automobiles et les organisations d'importation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zehnderhurter.ch\/fr\/movec-interfaces\/","og_locale":"fr_FR","og_type":"article","og_title":"movec - Interfaces - Zehnder &amp; Hurter AG","og_description":"movec interfaces OEM \u2013 Solutions num\u00e9riques pour les constructeurs automobiles et les organisations d'importation","og_url":"https:\/\/zehnderhurter.ch\/fr\/movec-interfaces\/","og_site_name":"Zehnder &amp; Hurter AG","article_modified_time":"2026-05-26T06:04:56+00:00","og_image":[{"width":1800,"height":500,"url":"https:\/\/zehnderhurter.ch\/wp-content\/uploads\/2025\/11\/OEM_Schnittstelle_Header.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"18 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zehnderhurter.ch\/fr\/movec-interfaces\/","url":"https:\/\/zehnderhurter.ch\/fr\/movec-interfaces\/","name":"movec - Interfaces - Zehnder &amp; Hurter AG","isPartOf":{"@id":"https:\/\/zehnderhurter.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zehnderhurter.ch\/fr\/movec-interfaces\/#primaryimage"},"image":{"@id":"https:\/\/zehnderhurter.ch\/fr\/movec-interfaces\/#primaryimage"},"thumbnailUrl":"https:\/\/zehnderhurter.ch\/wp-content\/uploads\/2025\/11\/OEM_Schnittstelle_Header.png","datePublished":"2025-11-18T08:47:59+00:00","dateModified":"2026-05-26T06:04:56+00:00","description":"movec interfaces OEM \u2013 Solutions num\u00e9riques pour les constructeurs automobiles et les organisations d'importation","breadcrumb":{"@id":"https:\/\/zehnderhurter.ch\/fr\/movec-interfaces\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zehnderhurter.ch\/fr\/movec-interfaces\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/zehnderhurter.ch\/fr\/movec-interfaces\/#primaryimage","url":"https:\/\/zehnderhurter.ch\/wp-content\/uploads\/2025\/11\/OEM_Schnittstelle_Header.png","contentUrl":"https:\/\/zehnderhurter.ch\/wp-content\/uploads\/2025\/11\/OEM_Schnittstelle_Header.png","width":1800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/zehnderhurter.ch\/fr\/movec-interfaces\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zehnderhurter.ch\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"movec &#8211; Interfaces"}]},{"@type":"WebSite","@id":"https:\/\/zehnderhurter.ch\/fr\/#website","url":"https:\/\/zehnderhurter.ch\/fr\/","name":"Zehnder &amp; Hurter AG","description":"Zehnder &amp; Hurter AG","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zehnderhurter.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/zehnderhurter.ch\/fr\/wp-json\/wp\/v2\/pages\/6629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zehnderhurter.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/zehnderhurter.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/zehnderhurter.ch\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/zehnderhurter.ch\/fr\/wp-json\/wp\/v2\/comments?post=6629"}],"version-history":[{"count":5,"href":"https:\/\/zehnderhurter.ch\/fr\/wp-json\/wp\/v2\/pages\/6629\/revisions"}],"predecessor-version":[{"id":6637,"href":"https:\/\/zehnderhurter.ch\/fr\/wp-json\/wp\/v2\/pages\/6629\/revisions\/6637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zehnderhurter.ch\/fr\/wp-json\/wp\/v2\/media\/6574"}],"wp:attachment":[{"href":"https:\/\/zehnderhurter.ch\/fr\/wp-json\/wp\/v2\/media?parent=6629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}